{"id":388,"count":1,"description":"","link":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/","name":"pilgrimage","slug":"pilgrimage","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pilgrimage Archivi - Don Carlo San Martino - Rigola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pilgrimage Archivi - Don Carlo San Martino - Rigola\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/\" \/>\n<meta property=\"og:site_name\" content=\"Don Carlo San Martino - Rigola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/tag\\\/pilgrimage\\\/\",\"url\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/tag\\\/pilgrimage\\\/\",\"name\":\"pilgrimage Archivi - Don Carlo San Martino - Rigola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/tag\\\/pilgrimage\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/tag\\\/pilgrimage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pilgrimage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/\",\"name\":\"Don Carlo San Martino - Rigola\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/#organization\",\"name\":\"Don Carlo San Martino - Rigola\",\"url\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-rigola-besana-brianza.svg\",\"contentUrl\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo-rigola-besana-brianza.svg\",\"width\":296.8079999999999927240423858165740966796875,\"height\":50.38199999999999789679350215010344982147216796875,\"caption\":\"Don Carlo San Martino - Rigola\"},\"image\":{\"@id\":\"https:\\\/\\\/rigola.doncarlosanmartino.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DonCarloSanMartinoRigola\\\/\",\"https:\\\/\\\/www.instagram.com\\\/doncarlosanmartino.rigola\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pilgrimage Archivi - Don Carlo San Martino - Rigola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/","og_locale":"en_US","og_type":"article","og_title":"pilgrimage Archivi - Don Carlo San Martino - Rigola","og_url":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/","og_site_name":"Don Carlo San Martino - Rigola","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/","url":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/","name":"pilgrimage Archivi - Don Carlo San Martino - Rigola","isPartOf":{"@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/tag\/pilgrimage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rigola.doncarlosanmartino.org\/en\/home\/"},{"@type":"ListItem","position":2,"name":"pilgrimage"}]},{"@type":"WebSite","@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/#website","url":"https:\/\/rigola.doncarlosanmartino.org\/en\/","name":"Don Carlo San Martino - Rigola","description":"","publisher":{"@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rigola.doncarlosanmartino.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/#organization","name":"Don Carlo San Martino - Rigola","url":"https:\/\/rigola.doncarlosanmartino.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/rigola.doncarlosanmartino.org\/wp-content\/uploads\/2026\/01\/logo-rigola-besana-brianza.svg","contentUrl":"https:\/\/rigola.doncarlosanmartino.org\/wp-content\/uploads\/2026\/01\/logo-rigola-besana-brianza.svg","width":296.8079999999999927240423858165740966796875,"height":50.38199999999999789679350215010344982147216796875,"caption":"Don Carlo San Martino - Rigola"},"image":{"@id":"https:\/\/rigola.doncarlosanmartino.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DonCarloSanMartinoRigola\/","https:\/\/www.instagram.com\/doncarlosanmartino.rigola\/"]}]}},"_links":{"self":[{"href":"https:\/\/rigola.doncarlosanmartino.org\/en\/wp-json\/wp\/v2\/tags\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rigola.doncarlosanmartino.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rigola.doncarlosanmartino.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rigola.doncarlosanmartino.org\/en\/wp-json\/wp\/v2\/posts?tags=388"},{"href":"https:\/\/rigola.doncarlosanmartino.org\/en\/wp-json\/wp\/v2\/laboratorio?tags=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}